{"id":4512,"date":"2018-04-02T12:17:08","date_gmt":"2018-04-02T10:17:08","guid":{"rendered":"http:\/\/toutcourtfestival.fr\/?p=4512"},"modified":"2018-04-02T14:12:35","modified_gmt":"2018-04-02T12:12:35","slug":"ca-tourne-action","status":"publish","type":"post","link":"https:\/\/toutcourtfestival.fr\/index.php\/2018\/04\/02\/ca-tourne-action\/","title":{"rendered":"\u00c7a tourne, Action !"},"content":{"rendered":"<div id=\"pl-4512\"  class=\"panel-layout\" ><div id=\"pg-4512-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-4512-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-4512-0-0-0\" class=\"so-panel widget widget_sow-headline panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-headline so-widget-sow-headline-default-6090f20097d1-4512\"\n\t\t\t\n\t\t><div class=\"sow-headline-container \">\n\t\t\t\t\t\t\t<h1 class=\"sow-headline\">\n\t\t\t\t\t\t\u00c7a tourne, action !\t\t\t\t\t\t<\/h1>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"decoration\">\n\t\t\t\t\t\t<div class=\"decoration-inside\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-4512-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-4512-1-0\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><div id=\"pgc-4512-1-1\"  class=\"panel-grid-cell panel-grid-cell-mobile-last\" ><div id=\"panel-4512-1-1-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p style=\"text-align: justify;\">Pour le Tout Court ! ces derni\u00e8res semaines auront \u00e9t\u00e9 particuli\u00e8rement actives entre ateliers et grand tournage dans Gisors!<\/p>\n<h1 style=\"text-align: justify;\"><span style=\"color: #0000ff;\">Tournage !<\/span><\/h1>\n<p style=\"text-align: justify;\">Le grand moment du mois de mars fut la participation du Tout Court ! \u00e0 un tournage professionnel !<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28701105_785189455025426_7856122635626269420_o.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4666 size-large\" src=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28701105_785189455025426_7856122635626269420_o-e1522662320389-1024x384.jpg?resize=1024%2C384\" alt=\"\" width=\"1024\" height=\"384\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Il s'agit d'un film produit par une association de production nomm\u00e9e Novum Film en partenariat avec le Tout Court !, la ville de Gisors, le lyc\u00e9e Louise Michel de Gisors, le lyc\u00e9e Camille Claudel de Vaur\u00e9al, la boucherie du centre de Gisors, mais aussi la r\u00e9gion Hauts-de-France (Pictanovo\/fond \u00e9mergence).\u00a0 Son r\u00e9alisateur est un jeune du Tout Court ! \u00e2g\u00e9 de 15 ans: le festival l'a accompagn\u00e9 dans la phase d'\u00e9criture du sc\u00e9nario pendant plus d'un an, jusqu'\u00e0 ce que Novum Film prenne en charge sa production.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/29570626_1255923577875138_4460220465697631497_n.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-4622 \" src=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/29570626_1255923577875138_4460220465697631497_n-e1522662621585-226x300.jpg?resize=252%2C335\" alt=\"\" width=\"252\" height=\"335\" srcset=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/29570626_1255923577875138_4460220465697631497_n-e1522662621585.jpg?resize=226%2C300&amp;ssl=1 226w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/29570626_1255923577875138_4460220465697631497_n-e1522662621585.jpg?w=640&amp;ssl=1 640w\" sizes=\"auto, (max-width: 252px) 100vw, 252px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">L'\u00e9quipe entourant le jeune r\u00e9alisateur \u00e9tait compos\u00e9 de chefs de postes professionnels et artistes du cin\u00e9ma (chef-op\u00e9rateur, assistant image, chef-d\u00e9co, ing\u00e9nieur du son, assistant r\u00e9al, scripte, \u00e9lectros, maquilleuse FX, plusieurs com\u00e9diens....) second\u00e9s par plusieurs stagiaires lyc\u00e9ens qu'ils encadraient, ainsi que par 4 b\u00e9n\u00e9voles du Tout Court !<\/p>\n<p style=\"text-align: justify;\">Le Tout Court ! a \u00e9galement permis \u00e0 pr\u00eat d'une cinquantaine de jeunes,\u00a0 enfants et lyc\u00e9ens, de participer au tournage :<\/p>\n<ul style=\"list-style-type: square; text-align: justify;\">\n<li>3 jeunes du Tout Court !, en plus du r\u00e9alisateur, en tant que stagiaires image, r\u00e9alisation\/script et son. Auparavant ils avaient particip\u00e9 aux phases de pr\u00e9paration, notamment les castings et r\u00e9p\u00e9titions acteurs.<\/li>\n<li>3 \u00e9l\u00e8ves du lyc\u00e9e Louise Michel, fili\u00e8re MELEC, en stagiaire \u00e9lectro et son.<\/li>\n<li>2 \u00e9l\u00e8ves du lyc\u00e9e Camille Claudel de Vaur\u00e9al en tant qu'acteurs du film<\/li>\n<li>6 \u00e9l\u00e8ves des lyc\u00e9es Louise Michel de Gisors et Camille Claudel de Vaur\u00e9al en tant que figurants<\/li>\n<li>1 acteur principal de 17 ans venu de Compi\u00e8gne<\/li>\n<li>2 acteurs principaux enfants venus d'Ile-de-France<\/li>\n<li>21 enfants de Gisors et alentours \u00e2g\u00e9s de 8 \u00e0 12 ans en tant que figurants.<\/li>\n<li style=\"text-align: justify;\">Enfin, 5 autres jeunes du Tout Court ! de l'an pass\u00e9 (au sein de l'atelier Cin\u00e9macam) avaient \u00e9galement particip\u00e9 \u00e0 plusieurs des phases d'\u00e9criture.<\/li>\n<\/ul>\n<p style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28701321_784326848445020_4610181917381035895_o.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4679\" src=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28701321_784326848445020_4610181917381035895_o-1024x768.jpg?resize=372%2C280\" alt=\"\" width=\"372\" height=\"280\" srcset=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28701321_784326848445020_4610181917381035895_o.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28701321_784326848445020_4610181917381035895_o.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28701321_784326848445020_4610181917381035895_o.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28701321_784326848445020_4610181917381035895_o.jpg?w=2048&amp;ssl=1 2048w\" sizes=\"auto, (max-width: 372px) 100vw, 372px\" \/>\u00a0 \u00a0 \u00a0\u00a0<\/a><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4624\" src=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/29354634_788671774677194_8026484515835828648_o-1024x576.jpg?resize=498%2C280\" alt=\"\" width=\"498\" height=\"280\" srcset=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/29354634_788671774677194_8026484515835828648_o.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/29354634_788671774677194_8026484515835828648_o.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/29354634_788671774677194_8026484515835828648_o.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/29354634_788671774677194_8026484515835828648_o.jpg?w=2048&amp;ssl=1 2048w\" sizes=\"auto, (max-width: 498px) 100vw, 498px\" \/><\/p>\n<p style=\"text-align: justify;\">Le tournage s'est d\u00e9roul\u00e9 majoritairement dans les locaux du lyc\u00e9e Louise Michel de Gisors sur deux week-ends: le premier dans un immense d\u00e9cor enti\u00e8rement construit dans la grande salle polyvalente du lyc\u00e9e, le deuxi\u00e8me dans des salles de classes, cours de r\u00e9cr\u00e9ation et une chambre d\u2019h\u00f4pital utilis\u00e9e par les \u00e9l\u00e8ves des fili\u00e8res m\u00e9dicales. Il a pu b\u00e9n\u00e9ficier d'un mat\u00e9riel professionnel tant pour la lumi\u00e8re que pour l'image et le son.<img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-4694 \" src=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28954557_785188438358861_4830441981292520918_o-e1522663212165-300x265.jpg?resize=232%2C205\" alt=\"\" width=\"232\" height=\"205\" srcset=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28954557_785188438358861_4830441981292520918_o-e1522663212165.jpg?resize=300%2C265&amp;ssl=1 300w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28954557_785188438358861_4830441981292520918_o-e1522663212165.jpg?resize=768%2C679&amp;ssl=1 768w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28954557_785188438358861_4830441981292520918_o-e1522663212165.jpg?resize=1024%2C906&amp;ssl=1 1024w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28954557_785188438358861_4830441981292520918_o-e1522663212165.jpg?w=1317&amp;ssl=1 1317w\" sizes=\"auto, (max-width: 232px) 100vw, 232px\" \/><\/p>\n<p style=\"text-align: justify;\">L'organisation sur le plateau \u00e9tait professionnelle: les chefs de postes des diff\u00e9rentes \u00e9quipes \u00e9taient orchestr\u00e9s par l'assistante r\u00e9alisatrice. Les jeunes impliqu\u00e9s et notamment les stagiaires, ont ainsi pu d\u00e9couvrir un v\u00e9ritable plateau de cin\u00e9ma avec toute l'organisation et le savoir-faire des diff\u00e9rents corps de m\u00e9tier, le tout tendu vers un m\u00eame but: faire le film voulu par le r\u00e9alisateur! Les jeunes se sont particuli\u00e8rement impliqu\u00e9s sous la direction des chefs de poste, fournissant un vrai travail parfois indispensabl<a href=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28953711_789157211295317_4061339451036608302_o.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-4625 alignright\" src=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28953711_789157211295317_4061339451036608302_o-1024x576.jpg?resize=374%2C210\" alt=\"\" width=\"374\" height=\"210\" srcset=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28953711_789157211295317_4061339451036608302_o.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28953711_789157211295317_4061339451036608302_o.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28953711_789157211295317_4061339451036608302_o.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28953711_789157211295317_4061339451036608302_o.jpg?w=2048&amp;ssl=1 2048w\" sizes=\"auto, (max-width: 374px) 100vw, 374px\" \/><\/a>e \u00e0 la bonne marche du film.\u00a0 Un grand bravo \u00e0 eux!<\/p>\n<p style=\"text-align: justify;\">Bref une belle aventure, qui n'est pas termin\u00e9e puisque maintenant commence la longue phase de post-production: montage, \u00e9talonnage, mixage... (on cherche d'ailleurs un \u00e9talonneur professionnel pour nous aider, si vous en connaissez contactez-nous!) On vise une premi\u00e8re du film, qui durera une quinzaine de minutes, pendant le Tout Court ! d\u00e9but juillet.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28953873_789156664628705_5154568188873772827_o.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4627 \" src=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28953873_789156664628705_5154568188873772827_o-e1522663021116-1024x435.jpg?resize=644%2C273\" alt=\"\" width=\"644\" height=\"273\" srcset=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28953873_789156664628705_5154568188873772827_o-e1522663021116.jpg?resize=1024%2C435&amp;ssl=1 1024w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28953873_789156664628705_5154568188873772827_o-e1522663021116.jpg?resize=300%2C127&amp;ssl=1 300w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28953873_789156664628705_5154568188873772827_o-e1522663021116.jpg?resize=768%2C326&amp;ssl=1 768w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28953873_789156664628705_5154568188873772827_o-e1522663021116.jpg?w=2037&amp;ssl=1 2037w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Une galerie de photos du tournage est visible <a href=\"http:\/\/toutcourtfestival.fr\/index.php\/tournage-le-proces\/\" target=\"_blank\" rel=\"noopener\">en cliquant ici.\u00a0<\/a><\/p>\n<p style=\"text-align: center;\">ngg_shortcode_0_placeholder<\/p>\n<h1 style=\"text-align: justify;\"><span style=\"color: #0000ff;\">Ateliers \u00e0 Gisors<\/span><\/h1>\n<p style=\"text-align: justify;\">Auparavant, vers la fin f\u00e9vrier, les jeunes du Tout Court ! et ceux du service jeunesse de la ville de Gisors (structures Bureau Info-Jeunesse et La Passerelle) - en tout une vingtaine de jeunes de 11 \u00e0 17 ans - ont particip\u00e9 \u00e0 deux belles journ\u00e9es d'ateliers cr\u00e9ation\/cin\u00e9ma.<\/p>\n<p style=\"text-align: justify;\">La premi\u00e8re journ\u00e9e fut consacr\u00e9e \u00e0 l'animation\/stop-motion avec Nicolas Bellanger, r\u00e9alisateur de films d'animation. En petits groupes, les jeunes ont d'abord imagin\u00e9s plusieurs petites histoires sur le th\u00e8me \"J'ai menti\". Ils les ont ensuite mis en sc\u00e8ne \u00e0 travers des story-boards, puis ils ont dessin\u00e9 et d\u00e9coup\u00e9 leurs \u00e9l\u00e9ments dans du papier (personnages, objets, paysages...) qu'ils ont ensuite anim\u00e9 sur un \"banc-titre\" (nomm\u00e9 ainsi car il reprend un dispositif utilis\u00e9 \u00e0 l'\u00e9poque du cin\u00e9ma pellicule pour cr\u00e9er et animer les titres et g\u00e9n\u00e9riques) en prenant image par image.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_160005.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4735\" src=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_160005-300x225.jpg?resize=300%2C225\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_160005.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_160005.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_160005.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_160005.jpg?w=2740&amp;ssl=1 2740w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_152543.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4734\" src=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_152543-300x225.jpg?resize=300%2C225\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_152543.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_152543.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_152543.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_152543.jpg?w=2740&amp;ssl=1 2740w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_1356100.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4733\" src=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_1356100-300x225.jpg?resize=300%2C225\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_1356100.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_1356100.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_1356100.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180227_1356100.jpg?w=2740&amp;ssl=1 2740w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">La deuxi\u00e8me journ\u00e9e avec le compositeur, musicien et bruiteur Jean-Carl Feldis, fut consacr\u00e9e pour les jeunes \u00e0 bruiter les films qu'ils avaient anim\u00e9s la veille, en passant par toutes les techniques et trucs et astuces de bruiteurs!<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_142730.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4737\" src=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_142730-300x225.jpg?resize=300%2C225\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_142730.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_142730.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_142730.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_142730.jpg?w=2740&amp;ssl=1 2740w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_150017.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4738\" src=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_150017-300x225.jpg?resize=300%2C225\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_150017.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_150017.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_150017.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_150017.jpg?w=2740&amp;ssl=1 2740w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_161200.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4739\" src=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_161200-300x225.jpg?resize=300%2C225\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_161200.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_161200.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_161200.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/20180228_161200.jpg?w=2740&amp;ssl=1 2740w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Le r\u00e9sultat final est visible en ligne ici:<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"1370\" height=\"771\" src=\"https:\/\/www.youtube.com\/embed\/qJxfjREp5Oo?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=fr-FR&#038;autohide=2&#038;start=1&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p style=\"text-align: justify;\">Ces ateliers furent l'occasion d'exp\u00e9rimenter une nouvelle forme de partenariat entre le festival Tout Court ! et le service jeunesse de Gisors. Une belle r\u00e9ussite qui sera amen\u00e9e \u00e0 se reproduire!<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-4512-1-2\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><div id=\"pg-4512-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-4512-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-4512-2-0-0\" class=\"so-panel widget widget_text panel-first-child panel-last-child\" data-index=\"2\" >\t\t\t<div class=\"textwidget\"><style>.entry-title {display:none;}<\/style>\n<\/div>\n\t\t<\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00c7a tourne, action ! <\/p>\n<p style=\"text-align: justify;\">Pour le Tout Court ! ces derni\u00e8res semaines auront \u00e9t\u00e9 particuli\u00e8rement actives entre ateliers et grand tournage dans Gisors!<\/p>\n<p> Tournage ! <\/p>\n<p style=\"text-align: justify;\">Le grand moment du mois de mars fut la participation du Tout Court ! \u00e0 un tournage professionnel !<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28701105_785189455025426_7856122635626269420_o.jpg\"><\/a><\/p>\n<p style=\"text-align: justify;\">Il &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/toutcourtfestival.fr\/index.php\/2018\/04\/02\/ca-tourne-action\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":1,"featured_media":4666,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-4512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","nodate","item-wrap"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/toutcourtfestival.fr\/wp-content\/uploads\/2018\/04\/28701105_785189455025426_7856122635626269420_o-e1540510806938.jpg?fit=1139%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8k6iw-1aM","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/toutcourtfestival.fr\/index.php\/wp-json\/wp\/v2\/posts\/4512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toutcourtfestival.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toutcourtfestival.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toutcourtfestival.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/toutcourtfestival.fr\/index.php\/wp-json\/wp\/v2\/comments?post=4512"}],"version-history":[{"count":0,"href":"https:\/\/toutcourtfestival.fr\/index.php\/wp-json\/wp\/v2\/posts\/4512\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/toutcourtfestival.fr\/index.php\/wp-json\/wp\/v2\/media\/4666"}],"wp:attachment":[{"href":"https:\/\/toutcourtfestival.fr\/index.php\/wp-json\/wp\/v2\/media?parent=4512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toutcourtfestival.fr\/index.php\/wp-json\/wp\/v2\/categories?post=4512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toutcourtfestival.fr\/index.php\/wp-json\/wp\/v2\/tags?post=4512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}